{"id":16231,"date":"2026-07-14T03:45:55","date_gmt":"2026-07-14T03:45:55","guid":{"rendered":"https:\/\/www.kunlonghardware.com\/?post_type=portfolio&#038;p=16231"},"modified":"2026-07-14T07:21:44","modified_gmt":"2026-07-14T07:21:44","slug":"handle-latch-sk1-903s","status":"publish","type":"portfolio","link":"https:\/\/www.kunlonghardware.com\/fr\/handle-latch-sk1-903s\/","title":{"rendered":"Poign\u00e9e \u00e0 loquet SK1-903S"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"16231\" class=\"elementor elementor-16231\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"portfolio\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5747f011 e-flex e-con-boxed e-con e-parent\" data-id=\"5747f011\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72103eac elementor-widget elementor-widget-pp-breadcrumbs\" data-id=\"72103eac\" data-element_type=\"widget\" data-settings=\"{&quot;breadcrumbs_type&quot;:&quot;seopress&quot;}\" data-widget_type=\"pp-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-breadcrumbs pp-breadcrumbs-seopress\">\n\t\t\t\t\t<nav  aria-label=\"mie de pain\"><ol class=\"breadcrumb\" itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li class=\"breadcrumb-item active\" aria-current=\"page\" itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Accueil<\/span><meta itemprop=\"position\" content=\"1\"><\/li><\/ol><\/nav>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-352b5f74 e-flex e-con-boxed e-con e-parent\" data-id=\"352b5f74\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4037c008 e-con-full e-flex e-con e-child\" data-id=\"4037c008\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e9b3004 elementor-skin-slideshow elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"1e9b3004\" data-element_type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;slideshow&quot;,&quot;centered_slides&quot;:&quot;yes&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"SK1-903S Poign\u00e9e \u00e0 loquet\" style=\"background-image: url(&#039;https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-9032.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"SK1-903S Poign\u00e9e \u00e0 loquet\" style=\"background-image: url(&#039;https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-9031.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Accessoires A-90-903\" style=\"background-image: url(&#039;https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/A-90-903.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Accessoires A-46-903\" style=\"background-image: url(&#039;https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/A-46-903.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Sch\u00e9ma d&#039;installation du SK1-903S\" style=\"background-image: url(&#039;https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903\u5b89\u88c5.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00e9c\u00e9dent\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Suivant\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper elementor-thumbnails-swiper swiper\" role=\"region region\" aria-roledescription=\"carousel carousel\" aria-label=\"Diapositives Diapositives\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"SK1-903S Poign\u00e9e \u00e0 loquet\" style=\"background-image: url(&#039;https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-9032.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"SK1-903S Poign\u00e9e \u00e0 loquet\" style=\"background-image: url(&#039;https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-9031.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Accessoires A-90-903\" style=\"background-image: url(&#039;https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/A-90-903.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Accessoires A-46-903\" style=\"background-image: url(&#039;https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/A-46-903.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Sch\u00e9ma d&#039;installation du SK1-903S\" style=\"background-image: url(&#039;https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903\u5b89\u88c5.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e059434 e-con-full e-flex e-con e-child\" data-id=\"5e059434\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2e184fa2 e-con-full e-flex e-con e-child\" data-id=\"2e184fa2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-634532d7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"634532d7\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b7ef763 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5b7ef763\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Prix unitaire :<\/b>US$68,52-78,3<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>MOQ :<\/b> pas de demande<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>D\u00e9lai d'ex\u00e9cution :<\/b>7~15 jours<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Application :<\/b>Cong\u00e9lateur combin\u00e9 ; Chambre froide ; Chambre d'essai<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-11b1f5b2 e-con-full e-flex e-con e-child\" data-id=\"11b1f5b2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3767323 elementor-align-center elementor-widget elementor-widget-bdt-advanced-button\" data-id=\"3767323\" data-element_type=\"widget\" data-widget_type=\"bdt-advanced-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-button-wrapper\">\n\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjIyMDYiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" class=\"bdt-ep-button bdt-ep-button-effect-e bdt-ep-button-size-md\">\n\t\t\t\t\t\t<div class=\"bdt-ep-button-content-wrapper bdt-flex bdt-flex-middle bdt-flex-center\" data-text=\"Request Quote\">\n\t\t\t\n\t\t\t<div class=\"bdt-ep-button-text\">\n\n\t\t\t\t<span class=\"avdbtn-text\">\n\t\t\t\t\tDemande de devis\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa2fd79 elementor-align-center elementor-widget elementor-widget-bdt-advanced-button\" data-id=\"aa2fd79\" data-element_type=\"widget\" data-widget_type=\"bdt-advanced-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-button-wrapper\">\n\t\t\t<a href=\"#\" class=\"bdt-ep-button bdt-ep-button-effect-e bdt-ep-button-size-md\">\n\t\t\t\t\t\t<div class=\"bdt-ep-button-content-wrapper bdt-flex bdt-flex-middle bdt-flex-center\" data-text=\"Catalog\">\n\t\t\t\n\t\t\t<div class=\"bdt-ep-button-text\">\n\n\t\t\t\t<span class=\"avdbtn-text\">\n\t\t\t\t\tCatalogue\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b95fbe e-flex e-con-boxed e-con e-parent\" data-id=\"b95fbe\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a24d518 e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"3a24d518\" data-element_type=\"widget\" data-settings=\"{&quot;tabs_justify_horizontal&quot;:&quot;stretch&quot;,&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"975492376\" aria-label=\"Onglets. Ouvrez des \u00e9l\u00e9ments avec Entrer ou Espace, fermez-les avec Echape et naviguez \u00e0 l&#039;aide des touches fl\u00e9ch\u00e9es.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-9754923761\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-9754923761\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tSp\u00e9cifications\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-9754923762\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-9754923762\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tDessins\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-9754923761\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-9754923761\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-16a7c87a e-con-full e-flex e-con e-child\" data-id=\"16a7c87a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55e788b3 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"55e788b3\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Caract\u00e9ristiques :<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Dot\u00e9 d'une fonction de force de compression \u00e9lev\u00e9e<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">La hauteur et la base plate peuvent \u00eatre choisies<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Commande synchronis\u00e9e des deux points de verrouillage de la porte de grande taille \u00e0 l'aide d'un tuyau de raccordement<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mat\u00e9riau en acier inoxydable, grande r\u00e9sistance \u00e0 la corrosion<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Mat\u00e9riau :<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Acier inoxydable (SUS304)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Finition :<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Polissage brillant<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Remarques :<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Il faut acheter s\u00e9par\u00e9ment un tube en acier inoxydable d'un diam\u00e8tre ext\u00e9rieur de 30 mm et d'une \u00e9paisseur comprise entre 1,0 et 1,5 mm ; il est recommand\u00e9 que sa longueur ne d\u00e9passe pas 500 mm.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Il est possible d'obtenir trois effets de liaison en ajoutant 1 pi\u00e8ce 1-903S-T<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-9754923762\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-9754923762\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\"elementor-element elementor-element-8ccff2e e-con-full e-grid e-con e-child\" data-id=\"8ccff2e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-127cf2fc elementor-widget elementor-widget-image\" data-id=\"127cf2fc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u4e3b\u56fe.webp\" class=\"attachment-large size-large wp-image-16247\" alt=\"Image principale du mod\u00e8le SK1-903S\" srcset=\"https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u4e3b\u56fe.webp 512w, https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u4e3b\u56fe-300x300.webp 300w, https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u4e3b\u56fe-150x150.webp 150w, https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u4e3b\u56fe-12x12.webp 12w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d586a3 elementor-widget elementor-widget-image\" data-id=\"4d586a3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u5c3a\u5bf8\u56fe-2.webp\" class=\"attachment-large size-large wp-image-16243\" alt=\"Plan cot\u00e9 du mod\u00e8le SK1-903S\" srcset=\"https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u5c3a\u5bf8\u56fe-2.webp 512w, https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u5c3a\u5bf8\u56fe-2-300x300.webp 300w, https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u5c3a\u5bf8\u56fe-2-150x150.webp 150w, https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u5c3a\u5bf8\u56fe-2-12x12.webp 12w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7731fe elementor-widget elementor-widget-image\" data-id=\"a7731fe\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u5c3a\u5bf8\u56fe.webp\" class=\"attachment-large size-large wp-image-16244\" alt=\"Plan cot\u00e9 du mod\u00e8le SK1-903S\" srcset=\"https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u5c3a\u5bf8\u56fe.webp 512w, https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u5c3a\u5bf8\u56fe-300x300.webp 300w, https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u5c3a\u5bf8\u56fe-150x150.webp 150w, https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u5c3a\u5bf8\u56fe-12x12.webp 12w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32e8aba elementor-widget elementor-widget-image\" data-id=\"32e8aba\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u538b\u529b\u6d4b\u8bd5.webp\" class=\"attachment-large size-large wp-image-16245\" alt=\"SK1-903S : Essai de pression\" srcset=\"https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u538b\u529b\u6d4b\u8bd5.webp 512w, https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u538b\u529b\u6d4b\u8bd5-300x300.webp 300w, https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u538b\u529b\u6d4b\u8bd5-150x150.webp 150w, https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u538b\u529b\u6d4b\u8bd5-12x12.webp 12w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97296ed elementor-widget elementor-widget-image\" data-id=\"97296ed\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u91cd\u91cf\u56fe.webp\" class=\"attachment-large size-large wp-image-16246\" alt=\"Tableau des poids du mod\u00e8le SK1-903S\" srcset=\"https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u91cd\u91cf\u56fe.webp 512w, https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u91cd\u91cf\u56fe-300x300.webp 300w, https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u91cd\u91cf\u56fe-150x150.webp 150w, https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-903S\u91cd\u91cf\u56fe-12x12.webp 12w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e2d617b e-flex e-con-boxed e-con e-parent\" data-id=\"6e2d617b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-717d46ca elementor-widget elementor-widget-heading\" data-id=\"717d46ca\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"i\"><\/span>Produits apparent\u00e9s<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1328a62 elementor-widget elementor-widget-ucaddon_post_carousel\" data-id=\"1328a62\" data-element_type=\"widget\" data-widget_type=\"ucaddon_post_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Post Carousel -->\n\t\t<link id='font-awesome-css' href='https:\/\/www.kunlonghardware.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/www.kunlonghardware.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='owl-carousel-css' href='https:\/\/www.kunlonghardware.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/owl-carousel-new\/assets\/owl.carousel.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='lity-css' href='https:\/\/www.kunlonghardware.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/lity\/lity.min.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Post Carousel *\/\n\n#uc_post_carousel_elementor_1328a62-wrapper{\n  min-height:1px;\n}\n\n#uc_post_carousel_elementor_1328a62 *{\n  box-sizing:border-box;\n}\n\n#uc_post_carousel_elementor_1328a62 .ue-grid-item-category a{\n  white-space: nowrap;\n}\n\n\n#uc_post_carousel_elementor_1328a62{\n  position:relative;\n}\n\n.uc_post_title{\n  font-size:21px;\n}\n\n#uc_post_carousel_elementor_1328a62 .ue-item{\n  transition:0.3s;\n  position:relative;\n}\n\n#uc_post_carousel_elementor_1328a62 .uc_image_carousel_placeholder{\n  position:relative;\n}\n\n#uc_post_carousel_elementor_1328a62 .ue_pos_carousel_image_overlay{\n  position:absolute;\n  top:0;\n  bottom:0;\n  left:0;\n  right:0;\n  transition:0.3s;\n}\n\n#uc_post_carousel_elementor_1328a62 .owl-stage{\n  display:flex;\n}\n\n#uc_post_carousel_elementor_1328a62 .uc_image_carousel_container_holder{\n  display: flex;\n  flex-direction: column;\n  height: 100%;\n}\n\n#uc_post_carousel_elementor_1328a62 .uc_image_carousel_content{\n  flex-grow: 1;\n  justify-content: space-between;}\n\n\n#uc_post_carousel_elementor_1328a62 .uc_carousel_item{\n  overflow:hidden;\n}\n\n#uc_post_carousel_elementor_1328a62 .owl-nav .owl-prev{\n    position:absolute;\n    display:inline-block;\n    text-align:center;  \t\n            top: 50% !important;\n  \t\ttransform: translate(0, -50%);\n    \t\n\n}\n#uc_post_carousel_elementor_1328a62 .owl-nav .owl-next{\n  position:absolute;\n  display:inline-block;\n  text-align:center;\n        top: 50% !important;\n  \t  transform: translate(0, -50%);\n  \t\n}\n\n\n#uc_post_carousel_elementor_1328a62 .owl-dots {\n  overflow:hidden;\n  display:flex !important;\n}\n\n#uc_post_carousel_elementor_1328a62 .owl-dot {\n  border-radius:50%;\n  display:inline-block;\n  padding: 0;\n}\n\n#uc_post_carousel_elementor_1328a62 .uc_more_btn{\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n}  \n\n#uc_post_carousel_elementor_1328a62 .uc_more_btn svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_post_carousel_elementor_1328a62 .uc_image_carousel_placeholder{\n  overflow:hidden;\n}\n#uc_post_carousel_elementor_1328a62 .uc_image_carousel_placeholder img{\n  display:block;\n  width:100%;\n}\n\n#uc_post_carousel_elementor_1328a62 .uc_image_carousel_content {\n  display:flex;\n  flex-direction:column;\n}\n\n\t\n\n\n\n\n\n\n\n\n\n#uc_post_carousel_elementor_1328a62 .ue-meta-data{  \n  display:flex !important;\n  flex-wrap: wrap;\n  line-height:1em;\n}\n\n#uc_post_carousel_elementor_1328a62 .ue-grid-item-meta-data{\n      display:inline-flex;\n      align-items:center;\n}\n\n.ue-grid-item-meta-data{\n  font-size:12px;\n}\n\n#uc_post_carousel_elementor_1328a62 .ue-grid-item-meta-data-icon{\n  line-height:1em;\n}\n\n#uc_post_carousel_elementor_1328a62 .ue-grid-item-meta-data-icon svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_post_carousel_elementor_1328a62 .ue-debug-meta{\n  padding:10px;\n  border:1px solid red;\n  position:relative;\n  line-height:1.5em;\n  font-size:11px;\n  width:100%;\n}\n\n\n\t#uc_post_carousel_elementor_1328a62 .owl-stage        {\n            transition-timing-function: linear!important;\n        }\n\n#uc_post_carousel_elementor_1328a62 .owl-nav .owl-prev.disabled,\n#uc_post_carousel_elementor_1328a62 .owl-nav .owl-next.disabled {\n   display: none;\n}\n\n<\/style>\n\n<div class=\"uc_overlay_image_carousel\" id=\"uc_post_carousel_elementor_1328a62-wrapper\">\n   <div class=\"uc_carousel owl-carousel owl-theme uc-items-wrapper\" data-custom-sethtml=\"true\"  data-id=\"\" id=\"uc_post_carousel_elementor_1328a62\" >\n   \t\t<div class=\"uc_image_carousel_container_holder uc_carousel_item ue-item\">\n  \n    <div class=\"uc_image_carousel_placeholder\">\n                 \n            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/06\/SK1-606R(3).webp\"  alt=\"Poign\u00e9e de compression SK1-606R\" width=\"512\" height=\"512\" title=\"SK1-606R (3)\"> \n        \t\n        <div class=\"ue_pos_carousel_image_overlay\"><\/div>\n          <\/div>\n  \n  \n    <div class=\"uc_image_carousel_content\" >\n        <div>\n          \n                            \n          \n                   <a href=\"https:\/\/www.kunlonghardware.com\/fr\/compression-handle-sk1-606r\/\">            <div class=\"uc_post_title\">Poign\u00e9e de compression SK1-606R<\/div>\n          <\/a>                   \n         \n         <div class=\"ue-meta-data\">\n                        \t\t\t            \n                                    \n            \n                        \n                        \n                       \n                      \n           \n             \n            \n          <\/div>          \n          \n                \n        <\/div>\n    \n            \n    \t<div class=\"ue-item-btn-holder\">   \n           <a target=\"_blank\" href=\"https:\/\/www.kunlonghardware.com\/fr\/compression-handle-sk1-606r\/\" class=\"uc_more_btn ue-dynamic-popup-single\">Lire la suite<\/a>\n\t\t<\/div>\n    \n          <\/div>\n    \n  \n    \n<\/div>\n<div class=\"uc_image_carousel_container_holder uc_carousel_item ue-item\">\n  \n    <div class=\"uc_image_carousel_placeholder\">\n                 \n            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-9032.webp\"  alt=\"SK1-903S Poign\u00e9e \u00e0 loquet\" width=\"512\" height=\"512\" title=\"SK1-903\"> \n        \t\n        <div class=\"ue_pos_carousel_image_overlay\"><\/div>\n          <\/div>\n  \n  \n    <div class=\"uc_image_carousel_content\" >\n        <div>\n          \n                            \n          \n                   <a href=\"https:\/\/www.kunlonghardware.com\/fr\/handle-latch-sk1-903s\/\">            <div class=\"uc_post_title\">Poign\u00e9e \u00e0 loquet SK1-903S<\/div>\n          <\/a>                   \n         \n         <div class=\"ue-meta-data\">\n                        \t\t\t            \n                                    \n            \n                        \n                        \n                       \n                      \n           \n             \n            \n          <\/div>          \n          \n                \n        <\/div>\n    \n            \n    \t<div class=\"ue-item-btn-holder\">   \n           <a target=\"_blank\" href=\"https:\/\/www.kunlonghardware.com\/fr\/handle-latch-sk1-903s\/\" class=\"uc_more_btn ue-dynamic-popup-single\">Lire la suite<\/a>\n\t\t<\/div>\n    \n          <\/div>\n    \n  \n    \n<\/div>\n<div class=\"uc_image_carousel_container_holder uc_carousel_item ue-item\">\n  \n    <div class=\"uc_image_carousel_placeholder\">\n                 \n            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK5-019.webp\"  alt=\"S\u00e9jour SK5-019\" width=\"512\" height=\"512\" title=\"Moulant\"> \n        \t\n        <div class=\"ue_pos_carousel_image_overlay\"><\/div>\n          <\/div>\n  \n  \n    <div class=\"uc_image_carousel_content\" >\n        <div>\n          \n                            \n          \n                   <a href=\"https:\/\/www.kunlonghardware.com\/fr\/stay-sk5-019\/\">            <div class=\"uc_post_title\">S\u00e9jour SK5-019<\/div>\n          <\/a>                   \n         \n         <div class=\"ue-meta-data\">\n                        \t\t\t            \n                                    \n            \n                        \n                        \n                       \n                      \n           \n             \n            \n          <\/div>          \n          \n                \n        <\/div>\n    \n            \n    \t<div class=\"ue-item-btn-holder\">   \n           <a target=\"_blank\" href=\"https:\/\/www.kunlonghardware.com\/fr\/stay-sk5-019\/\" class=\"uc_more_btn ue-dynamic-popup-single\">Lire la suite<\/a>\n\t\t<\/div>\n    \n          <\/div>\n    \n  \n    \n<\/div>\n<div class=\"uc_image_carousel_container_holder uc_carousel_item ue-item\">\n  \n    <div class=\"uc_image_carousel_placeholder\">\n                 \n            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/07\/SK1-840.webp\"  alt=\"Poign\u00e9e de compression SK1-840\" width=\"512\" height=\"512\" title=\"SK1-840\"> \n        \t\n        <div class=\"ue_pos_carousel_image_overlay\"><\/div>\n          <\/div>\n  \n  \n    <div class=\"uc_image_carousel_content\" >\n        <div>\n          \n                            \n          \n                   <a href=\"https:\/\/www.kunlonghardware.com\/fr\/compression-handle-sk1-840\/\">            <div class=\"uc_post_title\">Poign\u00e9e de compression SK1-840<\/div>\n          <\/a>                   \n         \n         <div class=\"ue-meta-data\">\n                        \t\t\t            \n                                    \n            \n                        \n                        \n                       \n                      \n           \n             \n            \n          <\/div>          \n          \n                \n        <\/div>\n    \n            \n    \t<div class=\"ue-item-btn-holder\">   \n           <a target=\"_blank\" href=\"https:\/\/www.kunlonghardware.com\/fr\/compression-handle-sk1-840\/\" class=\"uc_more_btn ue-dynamic-popup-single\">Lire la suite<\/a>\n\t\t<\/div>\n    \n          <\/div>\n    \n  \n    \n<\/div>\n<div class=\"uc_image_carousel_container_holder uc_carousel_item ue-item\">\n  \n    <div class=\"uc_image_carousel_placeholder\">\n                 \n            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/05\/SK5-017S2.webp\"  alt=\"Attraper SK5-017S\" width=\"512\" height=\"512\" title=\"SK5-017S(2)\"> \n        \t\n        <div class=\"ue_pos_carousel_image_overlay\"><\/div>\n          <\/div>\n  \n  \n    <div class=\"uc_image_carousel_content\" >\n        <div>\n          \n                            \n          \n                   <a href=\"https:\/\/www.kunlonghardware.com\/fr\/catch-sk5-017s\/\">            <div class=\"uc_post_title\">Attraper SK5-017S<\/div>\n          <\/a>                   \n         \n         <div class=\"ue-meta-data\">\n                        \t\t\t            \n                                    \n            \n                        \n                        \n                       \n                      \n           \n             \n            \n          <\/div>          \n          \n                \n        <\/div>\n    \n            \n    \t<div class=\"ue-item-btn-holder\">   \n           <a target=\"_blank\" href=\"https:\/\/www.kunlonghardware.com\/fr\/catch-sk5-017s\/\" class=\"uc_more_btn ue-dynamic-popup-single\">Lire la suite<\/a>\n\t\t<\/div>\n    \n          <\/div>\n    \n  \n    \n<\/div>\n<div class=\"uc_image_carousel_container_holder uc_carousel_item ue-item\">\n  \n    <div class=\"uc_image_carousel_placeholder\">\n                 \n            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/05\/SK5-017A2.webp\"  alt=\"Attraper SK5-017A\" width=\"512\" height=\"512\" title=\"SK5-017A(2)\"> \n        \t\n        <div class=\"ue_pos_carousel_image_overlay\"><\/div>\n          <\/div>\n  \n  \n    <div class=\"uc_image_carousel_content\" >\n        <div>\n          \n                            \n          \n                   <a href=\"https:\/\/www.kunlonghardware.com\/fr\/catch-sk5-017\/\">            <div class=\"uc_post_title\">Capture SK5-017<\/div>\n          <\/a>                   \n         \n         <div class=\"ue-meta-data\">\n                        \t\t\t            \n                                    \n            \n                        \n                        \n                       \n                      \n           \n             \n            \n          <\/div>          \n          \n                \n        <\/div>\n    \n            \n    \t<div class=\"ue-item-btn-holder\">   \n           <a target=\"_blank\" href=\"https:\/\/www.kunlonghardware.com\/fr\/catch-sk5-017\/\" class=\"uc_more_btn ue-dynamic-popup-single\">Lire la suite<\/a>\n\t\t<\/div>\n    \n          <\/div>\n    \n  \n    \n<\/div>\n<div class=\"uc_image_carousel_container_holder uc_carousel_item ue-item\">\n  \n    <div class=\"uc_image_carousel_placeholder\">\n                 \n            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/05\/SK5-016-1.webp\"  alt=\"Capture SK5-016-1\" width=\"512\" height=\"512\" title=\"SK5-016-1\"> \n        \t\n        <div class=\"ue_pos_carousel_image_overlay\"><\/div>\n          <\/div>\n  \n  \n    <div class=\"uc_image_carousel_content\" >\n        <div>\n          \n                            \n          \n                   <a href=\"https:\/\/www.kunlonghardware.com\/fr\/catch-sk5-016\/\">            <div class=\"uc_post_title\">Capture SK5-016<\/div>\n          <\/a>                   \n         \n         <div class=\"ue-meta-data\">\n                        \t\t\t            \n                                    \n            \n                        \n                        \n                       \n                      \n           \n             \n            \n          <\/div>          \n          \n                \n        <\/div>\n    \n            \n    \t<div class=\"ue-item-btn-holder\">   \n           <a target=\"_blank\" href=\"https:\/\/www.kunlonghardware.com\/fr\/catch-sk5-016\/\" class=\"uc_more_btn ue-dynamic-popup-single\">Lire la suite<\/a>\n\t\t<\/div>\n    \n          <\/div>\n    \n  \n    \n<\/div>\n<div class=\"uc_image_carousel_container_holder uc_carousel_item ue-item\">\n  \n    <div class=\"uc_image_carousel_placeholder\">\n                 \n            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kunlonghardware.com\/wp-content\/uploads\/2026\/05\/SK5-013.webp\"  alt=\"S\u00e9jour SK5-013\" width=\"512\" height=\"512\" title=\"SK5-013\"> \n        \t\n        <div class=\"ue_pos_carousel_image_overlay\"><\/div>\n          <\/div>\n  \n  \n    <div class=\"uc_image_carousel_content\" >\n        <div>\n          \n                            \n          \n                   <a href=\"https:\/\/www.kunlonghardware.com\/fr\/stay-sk5-013\/\">            <div class=\"uc_post_title\">S\u00e9jour SK5-013<\/div>\n          <\/a>                   \n         \n         <div class=\"ue-meta-data\">\n                        \t\t\t            \n                                    \n            \n                        \n                        \n                       \n                      \n           \n             \n            \n          <\/div>          \n          \n                \n        <\/div>\n    \n            \n    \t<div class=\"ue-item-btn-holder\">   \n           <a target=\"_blank\" href=\"https:\/\/www.kunlonghardware.com\/fr\/stay-sk5-013\/\" class=\"uc_more_btn ue-dynamic-popup-single\">Lire la suite<\/a>\n\t\t<\/div>\n    \n          <\/div>\n    \n  \n    \n<\/div>\n\n   <\/div>\t\n<\/div>\n\n\n<!-- end Post Carousel -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4338b8ce e-flex e-con-boxed e-con e-parent\" data-id=\"4338b8ce\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-560e0e9 e-con-full e-flex e-con e-child\" data-id=\"560e0e9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1779a936 elementor-widget elementor-widget-heading\" data-id=\"1779a936\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"i-2\"><\/span>Nous contacter<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4650b2b4 elementor-widget elementor-widget-text-editor\" data-id=\"4650b2b4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-page-id=\"HV8Ad72e0oNhz6xuCSoczxC2nTg\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-Man7dRyfFoEUvyxg04GcomMMngg\"><div data-page-id=\"XfdedT43qoPAwsx4ZGVc2yffnOd\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-RAeidIC5zoRDRHxO8J9cq2KHn7L\">Besoin d'une r\u00e9ponse rapide ? Contactez-nous d\u00e8s maintenant et notre \u00e9quipe vous r\u00e9pondra dans les 12 heures.<\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c02745b e-con-full e-flex e-con e-child\" data-id=\"7c02745b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a81f18f elementor-widget__width-initial elementor-widget-tablet__width-inherit premium-icon-box-center elementor-widget elementor-widget-premium-addon-icon-box\" data-id=\"4a81f18f\" data-element_type=\"widget\" data-widget_type=\"premium-addon-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"premium-icon-box-container-out\">\n\t\t\t\t<div class=\"premium-icon-box-container-in premium-icon-box-flex-top premium-icon-box-flex-ver-top\" >\n\t\t\t<div class=\"premium-icon-box-icon-container\">\n\n\t\t\t\t<div class=\"premium-icon-wrapper\">\n\t\t\t\t\t<i class=\"premium-icon-box-icon none fas fa-phone-volume\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t<div class=\"premium-icon-box-content-wrap premium-icon-box-cta-\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"premium-icon-box-text-wrap\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t<h3 class=\"premium-icon-box-title\">T\u00e9l :\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-icon-box-content\">\n\t\t\t\t\t\t\t<div data-page-id=\"HV8Ad72e0oNhz6xuCSoczxC2nTg\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\"><div class=\"old-record-id-Z5O4djLHbo1TDixan2ecZI8GnOh\"><div data-page-id=\"HV8Ad72e0oNhz6xuCSoczxC2nTg\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\"><div class=\"old-record-id-J24tdFh3hoeo7zx3R1XcrOcOnHf\">86-769-22687696<\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"premium-icon-box-big premium-icon-box-big-hover\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"premium-icon-box-icon fas fa-phone-volume\"><\/i>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40cb7256 elementor-widget__width-initial elementor-widget-tablet__width-inherit premium-icon-box-center elementor-widget elementor-widget-premium-addon-icon-box\" data-id=\"40cb7256\" data-element_type=\"widget\" data-widget_type=\"premium-addon-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"premium-icon-box-container-out\">\n\t\t\t\t<div class=\"premium-icon-box-container-in premium-icon-box-flex-top premium-icon-box-flex-ver-top\" >\n\t\t\t<div class=\"premium-icon-box-icon-container\">\n\n\t\t\t\t<div class=\"premium-icon-wrapper\">\n\t\t\t\t\t<i class=\"premium-icon-box-icon none fas fa-mobile-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t<div class=\"premium-icon-box-content-wrap premium-icon-box-cta-\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"premium-icon-box-text-wrap\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t<h3 class=\"premium-icon-box-title\">Mob :\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-icon-box-content\">\n\t\t\t\t\t\t\t<div data-page-id=\"HV8Ad72e0oNhz6xuCSoczxC2nTg\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\"><div class=\"old-record-id-Z5O4djLHbo1TDixan2ecZI8GnOh\">0086 18024916751<\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"premium-icon-box-big premium-icon-box-big-hover\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"premium-icon-box-icon fas fa-mobile-alt\"><\/i>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ca2a54b e-con-full e-flex e-con e-child\" data-id=\"7ca2a54b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e394e9b elementor-widget__width-initial elementor-widget-tablet__width-inherit premium-icon-box-center elementor-widget elementor-widget-premium-addon-icon-box\" data-id=\"6e394e9b\" data-element_type=\"widget\" data-widget_type=\"premium-addon-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"premium-icon-box-container-out\">\n\t\t\t\t<div class=\"premium-icon-box-container-in premium-icon-box-flex-top premium-icon-box-flex-ver-top\" >\n\t\t\t<div class=\"premium-icon-box-icon-container\">\n\n\t\t\t\t<div class=\"premium-icon-wrapper\">\n\t\t\t\t\t<i class=\"premium-icon-box-icon none fas fa-fax\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t<div class=\"premium-icon-box-content-wrap premium-icon-box-cta-\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"premium-icon-box-text-wrap\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t<h3 class=\"premium-icon-box-title\">Fax : \t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-icon-box-content\">\n\t\t\t\t\t\t\t<div data-page-id=\"HV8Ad72e0oNhz6xuCSoczxC2nTg\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\"><div class=\"old-record-id-Z5O4djLHbo1TDixan2ecZI8GnOh\"><div data-page-id=\"HV8Ad72e0oNhz6xuCSoczxC2nTg\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\"><div class=\"old-record-id-J24tdFh3hoeo7zx3R1XcrOcOnHf\">86-769-22687694<\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"premium-icon-box-big premium-icon-box-big-hover\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"premium-icon-box-icon fas fa-fax\"><\/i>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2cf6d141 e-con-full e-flex e-con e-child\" data-id=\"2cf6d141\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a7c6261 elementor-widget elementor-widget-bdt-wp-forms\" data-id=\"2a7c6261\" data-element_type=\"widget\" data-widget_type=\"bdt-wp-forms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-1903\"><form id=\"wpforms-form-1903\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"1903\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/fr\/wp-json\/wp\/v2\/portfolio\/16231?wpforms_form_id=1903\" data-token=\"96ded988526f3decb1b3ca2c64ea5950\" data-token-time=\"1784138400\" data-trp-original-action=\"\/fr\/wp-json\/wp\/v2\/portfolio\/16231?wpforms_form_id=1903\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-1903-field_4-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"4\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1903-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-1903-field_1\">Nom <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1903-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" aria-errormessage=\"wpforms-1903-field_1-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1903-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-1903-field_2\">Courriel <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-1903-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-1903-field_2-error\" required><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1903-field_10-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-1903-field_10\">Nom de l'entreprise<\/label><input type=\"text\" id=\"wpforms-1903-field_10\" class=\"wpforms-field-medium\" name=\"wpforms[fields][10]\" aria-errormessage=\"wpforms-1903-field_10-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1903-field_9-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-1903-field_9\">T\u00e9l\u00e9phone ou Whatsapp <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-1903-field_9\" class=\"wpforms-field-medium wpforms-field-required\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][9]\" aria-label=\"T\u00e9l\u00e9phone ou Whatsapp\" aria-errormessage=\"wpforms-1903-field_9-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-1903-field_7-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-1903-field_7\">Message <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-1903-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-1903-field_7-error\" required><\/textarea><\/div><div id=\"wpforms-1903-field_12-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-1903-field_12\">T\u00e9l\u00e9chargement de fichiers<\/label><div\n\t\tclass=\"wpforms-uploader\"\n\t\tdata-field-id=\"12\"\n\t\tdata-form-id=\"1903\"\n\t\tdata-input-name=\"wpforms_1903_12\"\n\t\tdata-extensions=\"jpg,jpeg,jpe,gif,png,bmp,tiff,tif,webp,avif,ico,heic,heif,heics,heifs,asf,asx,wmv,wmx,wm,avi,divx,mov,qt,mpeg,mpg,mpe,mp4,m4v,ogv,webm,mkv,3gp,3gpp,3g2,3gp2,txt,asc,c,cc,h,srt,csv,tsv,ics,rtx,css,vtt,mp3,m4a,m4b,aac,ra,ram,wav,x-wav,ogg,oga,flac,mid,midi,wma,wax,mka,rtf,pdf,class,tar,zip,gz,gzip,rar,7z,psd,xcf,doc,pot,pps,ppt,wri,xla,xls,xlt,xlw,mpp,docx,docm,dotx,dotm,xlsx,xlsm,xlsb,xltx,xltm,xlam,pptx,pptm,ppsx,ppsm,potx,potm,ppam,sldx,sldm,onetoc,onetoc2,onepkg,oxps,xps,odt,odp,ods,odg,odc,odb,odf,wp,wpd,key,numbers,pages,json\"\n\t\tdata-max-size=\"2147483648\"\n\t\tdata-max-file-number=\"1\"\n\t\tdata-post-max-size=\"2147483648\"\n\t\tdata-max-parallel-uploads=\"4\"\n\t\tdata-parallel-uploads=\"true\"\n\t\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg viewbox=\"0 0 1024 1024\" focusable=\"false\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"currentColor\" aria-hidden=\"true\">\n\t\t\t<path d=\"M885.2 446.3l-.2-.8-112.2-285.1c-5-16.1-19.9-27.2-36.8-27.2H281.2c-17 0-32.1 11.3-36.9 27.6L139.4 443l-.3.7-.2.8c-1.3 4.9-1.7 9.9-1 14.8-.1 1.6-.2 3.2-.2 4.8V830a60.9 60.9 0 0 0 60.8 60.8h627.2c33.5 0 60.8-27.3 60.9-60.8V464.1c0-1.3 0-2.6-.1-3.7.4-4.9 0-9.6-1.3-14.1zm-295.8-43l-.3 15.7c-.8 44.9-31.8 75.1-77.1 75.1-22.1 0-41.1-7.1-54.8-20.6S436 441.2 435.6 419l-.3-15.7H229.5L309 210h399.2l81.7 193.3H589.4zm-375 76.8h157.3c24.3 57.1 76 90.8 140.4 90.8 33.7 0 65-9.4 90.3-27.2 22.2-15.6 39.5-37.4 50.7-63.6h156.5V814H214.4V480.1z\"><\/path>\n\t\t<\/svg>\n\t\t<span class=\"modern-title\">Cliquez sur un fichier ou faites-le glisser dans cette zone pour le t\u00e9l\u00e9charger.<\/span>\n\n\t\t\t<\/div>\n<\/div>\n<input\n\t\ttype=\"text\"\n\t\tautocomplete=\"off\"\n\t\treadonly\n\t\tclass=\"dropzone-input\"\n\t\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\t\tid=\"wpforms-1903-field_12\"\n\t\tname=\"wpforms_1903_12\" \t\tvalue=\"\">\n<\/div><div id=\"wpforms-1903-field_11-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"11\"><input type=\"hidden\" id=\"wpforms-1903-field_11\" name=\"wpforms[fields][11]\" value=\"https:\/\/www.kunlonghardware.com\/fr\/wp-json\/wp\/v2\/portfolio\/16231\"><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" ><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"1903\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/www.kunlonghardware.com\/fr\/wp-json\/wp\/v2\/portfolio\/16231\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-1903\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Soumettre<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kunlonghardware.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"fr\"\/><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"featured_media":16189,"template":"","portfolio_categories":[52],"class_list":["post-16231","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-handle-latch"],"_links":{"self":[{"href":"https:\/\/www.kunlonghardware.com\/fr\/wp-json\/wp\/v2\/portfolio\/16231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kunlonghardware.com\/fr\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.kunlonghardware.com\/fr\/wp-json\/wp\/v2\/types\/portfolio"}],"version-history":[{"count":4,"href":"https:\/\/www.kunlonghardware.com\/fr\/wp-json\/wp\/v2\/portfolio\/16231\/revisions"}],"predecessor-version":[{"id":16250,"href":"https:\/\/www.kunlonghardware.com\/fr\/wp-json\/wp\/v2\/portfolio\/16231\/revisions\/16250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kunlonghardware.com\/fr\/wp-json\/wp\/v2\/media\/16189"}],"wp:attachment":[{"href":"https:\/\/www.kunlonghardware.com\/fr\/wp-json\/wp\/v2\/media?parent=16231"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.kunlonghardware.com\/fr\/wp-json\/wp\/v2\/portfolio_categories?post=16231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}